{"id":31,"date":"2008-02-28T18:40:14","date_gmt":"2008-02-28T16:40:14","guid":{"rendered":"https:\/\/www.gesund-heilfasten.de\/blog\/schmerzen-nach-weissheitszahn-extraktion\/"},"modified":"2025-12-24T16:30:30","modified_gmt":"2025-12-24T15:30:30","slug":"schmerzen-nach-weissheitszahn-extraktion","status":"publish","type":"post","link":"https:\/\/www.gesund-heilfasten.de\/blog\/schmerzen-nach-weissheitszahn-extraktion\/","title":{"rendered":"Schmerzen nach Wei\u00dfheitszahn-Extraktion"},"content":{"rendered":"<p>Ein Leser meines Newsletters und meiner Heilfasten Anleitung, schrieb mir folgende Krankengeschichte:<\/p>\n<p>Hallo Herr Gr\u00e4ber,<\/p>\n<p>\u00fcber Umwege bin ich auf Ihre Seite gekommen und damit auch an Ihre<br \/>\nAnleitung. In der n\u00e4chsten Woche m\u00f6chte ich Sie mit einem Freund<br \/>\ngemeinsam zum ersten Mal ausprobieren und ehrlich gesagt freue ich mich<br \/>\nauch schon sehr darauf.<\/p>\n<p>Allerdings geht es mir in dieser Mail um etwas anderes und ich w\u00fcrde<br \/>\nmich freuen, wenn Sie die Zeit finden, um sich das Folgende einmal<br \/>\ndurchzulesen und mir eventuelle Erfahrungen\/Empfehlungen mitteilen.<\/p>\n<p>Das ganze zieht sich in der jetzigen Form schon 10 Monate hin:<br \/>\nIch studiere und sitze demnach viel am Rechner.<br \/>\nNach einem unsanften Studieneinstieg musste ich ab dem zweiten Jahr ein<br \/>\npaar Kurse wiederholen, was ich aber &#8222;nebenbei&#8220; machen wollte, um nicht<br \/>\nin Verzug zu geraten. Die Folge war noch mehr Arbeit in der selben Zeit.<\/p>\n<p>Eine Theorie f\u00fcr meine Beschwerden ist nun, dass sich durch das Studium<br \/>\nder Stress bei mir immer mehr aufgestaut hat (k\u00f6rperlicher Ausgleich war<br \/>\nzwischenzeitig gleich Null).<\/p>\n<p>Im letzten M\u00e4rz nun war ich im Praktikum. Ich f\u00fchlte mich dort recht<br \/>\nwohl und hatte weniger zu tun als im Studium.<\/p>\n<p>Nach einigen Wochen hatte ich eine Entz\u00fcndung am Weisheitszahn (immer<br \/>\ndieser widerliche Geschmack im Mund vom Eiter)<\/p>\n<p>Das wurde vom Zahnarzt behandelt mittels Desinfektion. Sofort in der<br \/>\ndarauf folgenden Woche war die Entz\u00fcndung weg, allerdings hatte ich dann<br \/>\nurpl\u00f6tzlich enorm hohen Blutdruck bekommen und ich hatte einen \u00fcberaus<br \/>\nunangenehmen Druck im Kopf (insbesondere am Hinterkopf) teilweise<br \/>\nbegleitet von Schwindel. Und ich habe st\u00e4ndig gefroren<\/p>\n<p>In zwei N\u00e4chten hatte ich meinen Herzschlag unglaublich intensiv im Hals<br \/>\nund im ganzen Kopf gesp\u00fcrt und konnte \u00fcberhaupt nicht schlafen (v\u00f6llig<br \/>\nver\u00e4ngstigt). Am n\u00e4chsten Morgen war das dann wieder weg.<br \/>\nIch konnte tun was ich wollte (Fahrrad fahren und so weiter war kein<br \/>\nProblem) &#8230; ich wurde diese Sache (Blutdruck, Druck im Kopf) nicht mehr<br \/>\nlos.<\/p>\n<p>Damit fing der Arztmarathon an. Blutbild, Ultraschall, Herzultraschall,<br \/>\nUrin, 24h Blutdruck war alles v\u00f6llig in Ordnung (&#8230;hatte ich auch nicht<br \/>\nanders erwartet)<\/p>\n<p>Nun, mit steigender Verzweiflung (und dem Eindruck die liebe \u00c4rztin<br \/>\nsuchte nur nach einem Grund mich letztlich auf Blutdrucktabletten zu<br \/>\nsetzen) fing ich (wie wohl jeder) an selbst nachzuforschen.<br \/>\nErste Ma\u00dfnahme: Die Weisheitsz\u00e4hne kamen alle raus &#8211; Da sie entz\u00fcndet<br \/>\nwaren kann das zu diesen Beschwerden f\u00fchren hatte ich an mehreren<br \/>\nStellen gelesen.<\/p>\n<p>Damit war ich die schlimmsten Sachen los geworden. Was blieb war<br \/>\nmanchmal ein intensiv sp\u00fcrbarer Herzschlag (l\u00e4stig und zuweilen<br \/>\nAngsteinfl\u00f6\u00dfend)<\/p>\n<p>Was aber geblieben ist sind Verspannungen in der Kaumuskulatur, die<br \/>\nmeiner Meinung nach auch f\u00fcr das Druckgef\u00fchl am Hinterkopf und zu den<br \/>\nSeiten ausstrahlend sind. Weiterhin komme ich mir manchmal so vor als<br \/>\nw\u00e4r ich nicht ganz Herr meines K\u00f6rpers &#8211; schwierig zu beschreiben&#8230; Um<br \/>\nden Kopf herum ein wenig taub und im ganzen K\u00f6rper ein gewisses Unwohlsein.<\/p>\n<p>Meine eigentliche Haus\u00e4rztin kann mir dabei nat\u00fcrlich nicht helfen<br \/>\n(versucht aber wenigstens nicht mit irgendeiner Medikamentenkeule was<br \/>\nerreichen)<\/p>\n<p>Eine (vielleicht auch durchaus wahrscheinliche) Theorie ist nun, dass<br \/>\nmich im Moment der Stress der letzten Jahre an der Uni einholt. Ich<br \/>\nbem\u00fchte mich dann um viel Sport im Ausdauerbereich und hatte und habe<br \/>\ndamit auch keinerlei k\u00f6rperliche Probleme.<\/p>\n<p>Los geworden bin ich das ganze allerdings nicht. Ich habe es nach 2<br \/>\nJahren der enormen Stressbelastung, ohne nennenswerten Ausgleich aber<br \/>\nauch nicht erwartet.<\/p>\n<p>Zwischenzeitlich war ich beim Psychologen der Universit\u00e4t und dieser hat<br \/>\nmir best\u00e4tigt, dass es bei mir sehr nach einer vegetativen St\u00f6rung<br \/>\naussieht. Eine Behandlung bei einem befreundeten Kinesiologen hatte auch<br \/>\nnicht geholfen. Jedenfalls nicht dauerhaft.<\/p>\n<p>Als mir dann neben dem frieren st\u00e4ndig schwindelig war und ich oftmals<br \/>\nauch unbegr\u00fcndet gefroren habe sollte ich es mal mit Opipramol versuchen.<br \/>\nDa das immerhin kein eigentliches Blutdruckmedikament ist, hab ich es<br \/>\n(wenn auch etwas widerwillig) versucht.<\/p>\n<p>Damit bin ich die nervigsten Sachen los geworden. Etwas komisch war mir<br \/>\ndas ganze aber doch, weil niemand wei\u00df wie dieses Medikament \u00fcberhaupt<br \/>\nwirkt.<\/p>\n<p>Das meine Abschlussarbeit in diesen Zeitraum fiel (ich aber auch fertig<br \/>\nwerden wollte) war nat\u00fcrlich nicht das beste Timing, aber ich hab es<br \/>\nirgendwie alles noch gepackt.<\/p>\n<p>Soweit dem was ich Ihnen beschreiben wollte.<\/p>\n<p>Jetzt ist meine Frage, ob Ihnen das irgendwie bekannt vorkommt? Immerhin<br \/>\nmachen Ihre Homepage und Ihre E-Mails den Eindruck, dass sie in Ihrer<br \/>\nT\u00e4tigkeit mit vielen Menschen und deren Krankheiten in Kontakt kommen<br \/>\nund so manchem schon sehr geholfen haben.<br \/>\nFalls ja w\u00fcrde ich mich freuen, wenn sie mir Tips geben k\u00f6nnen, was ich<br \/>\ntun kann.<br \/>\nMomentan bin ich seit gut einer Woche dabei das Opipramol abzusetzen<br \/>\n(ich hoffe diesmal klappts) und will ab n\u00e4chsten Donnerstag das Fasten<br \/>\nnach Ihrer Anleitung durchf\u00fchren.<br \/>\nIch erhoffe mir damit die in der Anleitung beschriebene Entgiftung, die<br \/>\nhoffentlich auch zur Verbesserung meiner Gesundheit beitragen wird.<br \/>\nAnsonsten bin ich prinzipiell ein sportlicher Typ und achte auf eine<br \/>\nausgewogene Ern\u00e4hrung (was der studentische Geldbeutel eben zul\u00e4sst..)<br \/>\nF\u00fcr die Zeit danach will ich weiterhin viel Ausdauersport treiben und<br \/>\nich habe mich dazu f\u00fcr das kommende Sommersemester beurlauben lassen.<\/p>\n<p>Mein Hoffnung ist bis zum Herbst wieder v\u00f6llig gesund zu sein, damit ich<br \/>\ndann mein Studium fortf\u00fchren kann. Dann aber weiterhin mit regelm\u00e4\u00dfigem<br \/>\nAusgleich.<\/p>\n<p>Also falls sie anhand dessen was ich geschrieben habe noch einen Tip f\u00fcr<br \/>\nmich haben, was ich noch tun kann, dann w\u00e4re ich daf\u00fcr sehr dankbar.<br \/>\nSollten sie mir sonst noch etwas zu den beschriebenen Beschwerden sagen<br \/>\nk\u00f6nnen, w\u00e4re mir das auch hilfreich.<br \/>\nAnsonsten freue ich mich auf das Fasten und bin gespannt was ich damit<br \/>\nerreichen kann.<br \/>\n&#8230;Das Ergebnis k\u00f6nnte ich Ihnen ja dann auch noch mitteilen.<\/p>\n<p>*********************************************************<\/p>\n<p><strong>\u00dcbrigens: Wenn Sie solche Informationen interessieren, dann fordern Sie unbedingt meinen Heilfasten-Newsletter dazu an:<\/strong><br \/>\n<script type=\"text\/javascript\" src=\"https:\/\/rene-graeber.de\/view_webform_v2.js?u=v9&#038;webforms_id=poWoP\"><\/script><\/p>\n<p>*********************************************************<\/p>\n<p>Als Erstes muss ich immer erst einmal sagen, dass ich keine Beratung, Empfehlung oder \u00e4hnliches per email abgebe. Das w\u00e4re nicht seri\u00f6s und ist mir nach meiner Heilpraktiker-Standesordnung auch nicht gestattet.<\/p>\n<p>Ich kann aber schreiben, was ich in vergleichbaren F\u00e4llen &#8222;denken&#8220; oder tun w\u00fcrde.<\/p>\n<p>Deswegen habe ich diesen Fall einmal genommen, weil er die Hilflosigkeit des &#8222;Facharzttums&#8220; aufzeigt. Nat\u00fcrlich bin ich dankbar, wenn ich einen Zahnarzt habe, der mir meinen kaputten Zahn zieht.<\/p>\n<p>Aber das obige Beispiel ist typisch, was manche Menschen an Odyseen hinter sich haben.<\/p>\n<p>***********************************************************<br \/>\nHier sind also meine Gedanken:<\/p>\n<p>Das Problem ist, dass das Problem mit der Extraktion des Wei\u00dfheitszahns nicht beseitigt war.<\/p>\n<p>Ich denke an folgendes:<\/p>\n<p>a) nochmaliges Panorama-R\u00f6ntgen des gesamten Kiefers. Es sollte kontrolliert werden, ob noch Zysten, Granulome oder Reste der Z\u00e4hne vergessen wurden.<\/p>\n<p>Wenn diese beseitigt w\u00fcrden, kann der Spuck sofort vorbei sein. Dazu braucht man aber einen aufgeschlossenen versierten Zahnarzt und die sind schwer zu finden!<\/p>\n<p>b) vermutlich wurden Antibiotika eingesetzt. In diesem Fall kommen weitere Probleme hinzu. Ich gebe daraufhin immer symptomatisch: Notakehl D5 Tropfen 3 mal 5 Tropfen t\u00e4glich, drei Wochen. Und jede Woche einmal Sulfur D12 zwei Tabletten. Auch drei Wochen. Das ist aber nur ein sehr allgemeines Schema, dass f\u00fcr den einzelnen Fall ver\u00e4ndert werden muss.<\/p>\n<p>c) Durch die Zahnextraktion kann der Aufbiss der Z\u00e4hne ver\u00e4ndert worden sein &#8211; und das ist das Wahrscheinlichste: eine Subluxation (Blockierung) des Kiefergelenks, eventuell auch des Atlantooccipitalgelenks.<\/p>\n<p>Das sollte jemand kontrollieren und auch gleich behandeln, der sich damit auskennt: ein Manualtherapeut, Chiropraktiker oder ein Osteopath.<\/p>\n<p>Punkt C) w\u00e4re das was ich zuerst machen w\u00fcrde. Dazu braucht man wieder jemand der das kann&#8230;<\/p>\n<p><strong>\u00dcbrigens: Wenn Sie solche Informationen interessieren, dann fordern Sie unbedingt meinen kostenlosen Praxis-Newsletter &#8222;Unabh\u00e4ngig. Nat\u00fcrlich. Klare Kante.&#8220; dazu an:<\/strong><br \/>\n<script type=\"text\/javascript\" src=\"https:\/\/rene-graeber.de\/view_webform_v2.js?u=v9&#038;webforms_id=pL1KE\"><\/script><\/p>\n<p>Beitragsbild: pixabay.com &#8211; Sammy-Sander<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ein Leser meines Newsletters und meiner Heilfasten Anleitung, schrieb mir folgende Krankengeschichte: Hallo Herr Gr\u00e4ber, \u00fcber Umwege bin ich auf Ihre Seite gekommen und damit auch an Ihre Anleitung. In der n\u00e4chsten Woche m\u00f6chte ich Sie mit einem Freund gemeinsam zum ersten Mal ausprobieren und ehrlich gesagt freue ich mich auch schon sehr darauf. Allerdings [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2823,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[264],"class_list":["post-31","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-beschwerden-und-krankheiten","tag-weissheitszahn-extraktion"],"_links":{"self":[{"href":"https:\/\/www.gesund-heilfasten.de\/blog\/wp-json\/wp\/v2\/posts\/31","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gesund-heilfasten.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gesund-heilfasten.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gesund-heilfasten.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gesund-heilfasten.de\/blog\/wp-json\/wp\/v2\/comments?post=31"}],"version-history":[{"count":6,"href":"https:\/\/www.gesund-heilfasten.de\/blog\/wp-json\/wp\/v2\/posts\/31\/revisions"}],"predecessor-version":[{"id":3728,"href":"https:\/\/www.gesund-heilfasten.de\/blog\/wp-json\/wp\/v2\/posts\/31\/revisions\/3728"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gesund-heilfasten.de\/blog\/wp-json\/wp\/v2\/media\/2823"}],"wp:attachment":[{"href":"https:\/\/www.gesund-heilfasten.de\/blog\/wp-json\/wp\/v2\/media?parent=31"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gesund-heilfasten.de\/blog\/wp-json\/wp\/v2\/categories?post=31"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gesund-heilfasten.de\/blog\/wp-json\/wp\/v2\/tags?post=31"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}