{"id":569,"date":"2011-03-18T10:22:54","date_gmt":"2011-03-18T09:22:54","guid":{"rendered":"https:\/\/www.gesund-heilfasten.de\/diaet\/blog\/?p=569"},"modified":"2023-11-22T20:23:03","modified_gmt":"2023-11-22T19:23:03","slug":"wenn-der-sensenmann-die-diaetpille-bringt","status":"publish","type":"post","link":"https:\/\/www.gesund-heilfasten.de\/diaet\/blog\/wenn-der-sensenmann-die-diaetpille-bringt\/","title":{"rendered":"Wenn der Sensenmann die Di\u00e4tpille bringt"},"content":{"rendered":"<p>In einer <a href=\"https:\/\/sante-medecine.commentcamarche.net\/faq\/5225-la-liste-des-77-medicaments-mis-sous-surveillance-par-l-afssaps\" target=\"_blank\" rel=\"noopener\">Liste mit 77 Medikamenten<\/a> gibt die Pharmaindustrie in Frankreich nun offen bekannt, welche Mittel auf dem franz\u00f6sischen Markt gesundheitssch\u00e4dlich sind. Nach dem Skandal um die Di\u00e4t-Pille &#8222;Mediator&#8220; musste der franz\u00f6sische Pr\u00e4sident Sarkozy reagieren und versprach eine neue Offenheit gegen\u00fcber der Bev\u00f6lkerung.<\/p>\n<p>Das <a href=\"https:\/\/www.gesund-heilfasten.de\/schlankheitsmittel\/\">Schlankheitsmittel<\/a> &#8222;Mediator&#8220; kam erstmals 1976 auf den Markt und wurde haupts\u00e4chlich \u00fcbergewichtigen Diabetikern verschrieben. Hergestellt wurde sie durch \u201eServier\u201c, dem zweitgr\u00f6\u00dften Pharmakonzern Frankreichs, in dem unter anderem auch viele ehemalige Minister und Abgeordnete als Lobbyisten t\u00e4tig waren, wodurch ein Wechselspiel aus Verbreitung und Interessenwahrung entstand.<\/p>\n<p><!--more-->Erst 2009 wurde von der Pharmaaufsicht eine gr\u00f6\u00dfere Warnung herausgegeben, die das Produkt \u201eMediator\u201c als gesundheitssch\u00e4dlich einstufte und vom Markt nahm, da es zu <a href=\"https:\/\/www.gesund-heilfasten.de\/folgen-uebergewicht\/\">Bluthochdruck<\/a> und Herzklappensch\u00e4den f\u00fchrt. Es hie\u00df, dass bereits hunderte Patienten durch die Nebenwirkungen des angeblichen Schlankmachers gestorben seien, die heutigen Annahmen gehen allerdings bereits von 2000 Menschen aus, die Opfer des Medikaments geworden sind.<\/p>\n<p><strong>\u00dcbrigens: Wenn Dich solche Informationen interessieren, dann fordere unbedingt meinen kostenlosen Abnehm-Newsletter dazu an:<\/strong><br \/>\n<script type=\"text\/javascript\" src=\"https:\/\/rene-graeber.de\/view_webform_v2.js?u=v9&#038;webforms_id=pQWy2\"><\/script><\/p>\n<p><strong>Die Franzosen zeigten sich schockiert, gerade weil die Nebenwirkungen seit langem bekannt waren, ohne dass rechtzeitig reagiert wurde. <\/strong>Seit Mitte der Neunziger Jahre wurden wiederholt Warnungen \u00fcber &#8222;Mediator&#8220; herausgegeben, w\u00e4hrend andere L\u00e4nder sich weigerten, das Medikament auf den Markt zu bringen. Durch eine zu hohe Toleranz bei der Pharmakontrolle wurde das Mittel in Frankreich dagegen weiterhin verkauft.<\/p>\n<p>Seit diesem Vorfall ist unbestritten, dass das Pharmasystem Frankreichs durch eine gef\u00e4hrliche Vermischung aus medizinischen, wirtschaftlichen und politischen Interessen gepr\u00e4gt ist, die auf Kosten des B\u00fcrgers und kranker Menschen gehen.<\/p>\n<p>Durch den Skandal konnte nun etwas Licht in diese Machenschaften gebracht werden, was die Franzosen allerdings nicht beruhigt, sondern ihnen lediglich best\u00e4tigt, wie unsicher die Auswahl der auf dem Markt zu erhaltenen Medikamente tats\u00e4chlich ist.<\/p>\n<p>Der Firmenchef des Konzerns \u201eServier\u201c, Jacques Servier, muss sich nun im Alter von 88 Jahren vor Gericht verantworten. Seinem Pharmakonzern wurde u. a. Betrug, Vergiftung und fahrl\u00e4ssige T\u00f6tung vorgeworfen.<\/p>\n<p>Die franz\u00f6sische Regierung bedauert die Vorf\u00e4lle und versprach, einen Opferfond einzurichten wie auch das Pharmasystem zu reformieren. Die herausgegebene Liste enth\u00e4lt unter anderem Medikamente wie die &#8222;Pille danach&#8220; bishin zu einem schadhaften Meningitis-Impfstoff.<\/p>\n<p><strong>Ab sofort, so das Versprechen, sollen Medikamente nur dann zugelassen werden, wenn sie in ihrer Wirkung besser als vorhandene Mittel sind, auch m\u00fcssen insbesondere Pharmaindustrien beweisen, dass ihre Mittel unsch\u00e4dlich sind.<\/strong><\/p>\n<p>Ein solcher Skandal ist in der heutigen Zeit unverantwortlich. Medikamente sollten der Heilung dienen und nicht den Tod verursachen.<\/p>\n<p><strong>Mehr zum Thema:<\/strong><\/p>\n<ul>\n<li><a href=\"https:\/\/naturheilt.com\/blog\/tag\/medikamentenskandale\/\" target=\"_blank\" rel=\"noopener\">Medikamentenskandale in Deutschland<\/a><\/li>\n<li><a href=\"https:\/\/sante-medecine.commentcamarche.net\/faq\/5225-la-liste-des-77-medicaments-mis-sous-surveillance-par-l-afssaps\" target=\"_blank\" rel=\"noopener\">Die Liste der 77 Medikamente (in franz. Sprache)<\/a><\/li>\n<\/ul>\n<p><strong>\u00dcbrigens: Wenn Sie solche Informationen interessieren, dann fordern Sie unbedingt meinen kostenlosen Praxis-Newsletter &#8222;Unabh\u00e4ngig. Nat\u00fcrlich. Klare Kante.&#8220; dazu an:<\/strong><br \/>\n<script type=\"text\/javascript\" src=\"https:\/\/rene-graeber.de\/view_webform_v2.js?u=v9&#038;webforms_id=pL1KE\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In einer Liste mit 77 Medikamenten gibt die Pharmaindustrie in Frankreich nun offen bekannt, welche Mittel auf dem franz\u00f6sischen Markt gesundheitssch\u00e4dlich sind. Nach dem Skandal um die Di\u00e4t-Pille &#8222;Mediator&#8220; musste der franz\u00f6sische Pr\u00e4sident Sarkozy reagieren und versprach eine neue Offenheit gegen\u00fcber der Bev\u00f6lkerung. Das Schlankheitsmittel &#8222;Mediator&#8220; kam erstmals 1976 auf den Markt und wurde haupts\u00e4chlich [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1659,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,5],"tags":[],"class_list":["post-569","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-schlankheitsmittel","category-diaten"],"rttpg_featured_image_url":{"full":["https:\/\/www.gesund-heilfasten.de\/diaet\/blog\/wp-content\/uploads\/2015\/01\/pille_tabletten_pixabay.com-padrinan.jpg",1280,851,false],"landscape":["https:\/\/www.gesund-heilfasten.de\/diaet\/blog\/wp-content\/uploads\/2015\/01\/pille_tabletten_pixabay.com-padrinan.jpg",1280,851,false],"portraits":["https:\/\/www.gesund-heilfasten.de\/diaet\/blog\/wp-content\/uploads\/2015\/01\/pille_tabletten_pixabay.com-padrinan.jpg",1280,851,false],"thumbnail":["https:\/\/www.gesund-heilfasten.de\/diaet\/blog\/wp-content\/uploads\/2015\/01\/pille_tabletten_pixabay.com-padrinan-150x150.jpg",80,80,true],"medium":["https:\/\/www.gesund-heilfasten.de\/diaet\/blog\/wp-content\/uploads\/2015\/01\/pille_tabletten_pixabay.com-padrinan-300x199.jpg",300,199,true],"large":["https:\/\/www.gesund-heilfasten.de\/diaet\/blog\/wp-content\/uploads\/2015\/01\/pille_tabletten_pixabay.com-padrinan-1024x681.jpg",1024,681,true],"1536x1536":["https:\/\/www.gesund-heilfasten.de\/diaet\/blog\/wp-content\/uploads\/2015\/01\/pille_tabletten_pixabay.com-padrinan.jpg",1280,851,false],"2048x2048":["https:\/\/www.gesund-heilfasten.de\/diaet\/blog\/wp-content\/uploads\/2015\/01\/pille_tabletten_pixabay.com-padrinan.jpg",1280,851,false],"widget":["https:\/\/www.gesund-heilfasten.de\/diaet\/blog\/wp-content\/uploads\/2015\/01\/pille_tabletten_pixabay.com-padrinan.jpg",36,24,false],"square":["https:\/\/www.gesund-heilfasten.de\/diaet\/blog\/wp-content\/uploads\/2015\/01\/pille_tabletten_pixabay.com-padrinan.jpg",180,120,false],"featured":["https:\/\/www.gesund-heilfasten.de\/diaet\/blog\/wp-content\/uploads\/2015\/01\/pille_tabletten_pixabay.com-padrinan.jpg",647,430,false],"featured_large":["https:\/\/www.gesund-heilfasten.de\/diaet\/blog\/wp-content\/uploads\/2015\/01\/pille_tabletten_pixabay.com-padrinan.jpg",948,630,false],"extra_large":["https:\/\/www.gesund-heilfasten.de\/diaet\/blog\/wp-content\/uploads\/2015\/01\/pille_tabletten_pixabay.com-padrinan.jpg",1280,851,false],"portfolio":["https:\/\/www.gesund-heilfasten.de\/diaet\/blog\/wp-content\/uploads\/2015\/01\/pille_tabletten_pixabay.com-padrinan.jpg",495,329,false],"portfolio_small":["https:\/\/www.gesund-heilfasten.de\/diaet\/blog\/wp-content\/uploads\/2015\/01\/pille_tabletten_pixabay.com-padrinan.jpg",260,173,false],"gallery":["https:\/\/www.gesund-heilfasten.de\/diaet\/blog\/wp-content\/uploads\/2015\/01\/pille_tabletten_pixabay.com-padrinan.jpg",845,562,false],"magazine":["https:\/\/www.gesund-heilfasten.de\/diaet\/blog\/wp-content\/uploads\/2015\/01\/pille_tabletten_pixabay.com-padrinan.jpg",564,375,false],"masonry":["https:\/\/www.gesund-heilfasten.de\/diaet\/blog\/wp-content\/uploads\/2015\/01\/pille_tabletten_pixabay.com-padrinan.jpg",705,469,false],"entry_with_sidebar":["https:\/\/www.gesund-heilfasten.de\/diaet\/blog\/wp-content\/uploads\/2015\/01\/pille_tabletten_pixabay.com-padrinan.jpg",483,321,false],"entry_without_sidebar":["https:\/\/www.gesund-heilfasten.de\/diaet\/blog\/wp-content\/uploads\/2015\/01\/pille_tabletten_pixabay.com-padrinan.jpg",636,423,false]},"rttpg_author":{"display_name":"Ren\u00e9 Gr\u00e4ber","author_link":"https:\/\/www.gesund-heilfasten.de\/diaet\/blog\/author\/3d3f44be47d7c9ce\/"},"rttpg_comment":1,"rttpg_category":"<a href=\"https:\/\/www.gesund-heilfasten.de\/diaet\/blog\/category\/schlankheitsmittel\/\" rel=\"category tag\">Abnehmmittel<\/a> <a href=\"https:\/\/www.gesund-heilfasten.de\/diaet\/blog\/category\/diaten\/\" rel=\"category tag\">Di\u00e4ten Aktuell<\/a>","rttpg_excerpt":"In einer Liste mit 77 Medikamenten gibt die Pharmaindustrie in Frankreich nun offen bekannt, welche Mittel auf dem franz\u00f6sischen Markt gesundheitssch\u00e4dlich sind. Nach dem Skandal um die Di\u00e4t-Pille &#8222;Mediator&#8220; musste der franz\u00f6sische Pr\u00e4sident Sarkozy reagieren und versprach eine neue Offenheit gegen\u00fcber der Bev\u00f6lkerung. Das Schlankheitsmittel &#8222;Mediator&#8220; kam erstmals 1976 auf den Markt und wurde haupts\u00e4chlich&hellip;","_links":{"self":[{"href":"https:\/\/www.gesund-heilfasten.de\/diaet\/blog\/wp-json\/wp\/v2\/posts\/569","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gesund-heilfasten.de\/diaet\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gesund-heilfasten.de\/diaet\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gesund-heilfasten.de\/diaet\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gesund-heilfasten.de\/diaet\/blog\/wp-json\/wp\/v2\/comments?post=569"}],"version-history":[{"count":6,"href":"https:\/\/www.gesund-heilfasten.de\/diaet\/blog\/wp-json\/wp\/v2\/posts\/569\/revisions"}],"predecessor-version":[{"id":1826,"href":"https:\/\/www.gesund-heilfasten.de\/diaet\/blog\/wp-json\/wp\/v2\/posts\/569\/revisions\/1826"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gesund-heilfasten.de\/diaet\/blog\/wp-json\/wp\/v2\/media\/1659"}],"wp:attachment":[{"href":"https:\/\/www.gesund-heilfasten.de\/diaet\/blog\/wp-json\/wp\/v2\/media?parent=569"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gesund-heilfasten.de\/diaet\/blog\/wp-json\/wp\/v2\/categories?post=569"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gesund-heilfasten.de\/diaet\/blog\/wp-json\/wp\/v2\/tags?post=569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}